{"id":401,"date":"2015-06-04T18:50:08","date_gmt":"2015-06-04T18:50:08","guid":{"rendered":"http:\/\/set-goblen.ro\/blog\/wp-content\/uploads\/2015\/06\/82.jpg"},"modified":"2015-06-04T18:50:08","modified_gmt":"2015-06-04T18:50:08","slug":"8-3","status":"inherit","type":"attachment","link":"http:\/\/set-goblen.ro\/blog\/floare-nemuritoare-diagrame-goblen-gratis\/8-3\/","title":{"rendered":"8"},"author":1,"comment_status":"open","ping_status":"open","template":"","meta":[],"description":{"rendered":"<div class=\"addtoany_share_save_container addtoany_content_top\"><div class=\"a2a_kit a2a_kit_size_32 addtoany_list a2a_target\" id=\"wpa2a_1\"><a class=\"a2a_button_facebook\" href=\"http:\/\/www.addtoany.com\/add_to\/facebook?linkurl=http%3A%2F%2Fset-goblen.ro%2Fblog%2Ffloare-nemuritoare-diagrame-goblen-gratis%2F8-3%2F&amp;linkname=8\" title=\"Facebook\" rel=\"nofollow\" target=\"_blank\"><\/a><a class=\"a2a_button_twitter\" href=\"http:\/\/www.addtoany.com\/add_to\/twitter?linkurl=http%3A%2F%2Fset-goblen.ro%2Fblog%2Ffloare-nemuritoare-diagrame-goblen-gratis%2F8-3%2F&amp;linkname=8\" title=\"Twitter\" rel=\"nofollow\" target=\"_blank\"><\/a><a class=\"a2a_button_google_plus\" href=\"http:\/\/www.addtoany.com\/add_to\/google_plus?linkurl=http%3A%2F%2Fset-goblen.ro%2Fblog%2Ffloare-nemuritoare-diagrame-goblen-gratis%2F8-3%2F&amp;linkname=8\" title=\"Google+\" rel=\"nofollow\" target=\"_blank\"><\/a><a class=\"a2a_dd addtoany_share_save\" href=\"https:\/\/www.addtoany.com\/share_save\"><\/a>\n<script type=\"text\/javascript\"><!--\nwpa2a.script_load();\n\/\/--><\/script>\n<\/div><\/div><p class=\"attachment\"><a href='http:\/\/set-goblen.ro\/blog\/wp-content\/uploads\/2015\/06\/82.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"http:\/\/set-goblen.ro\/blog\/wp-content\/uploads\/2015\/06\/82-212x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"http:\/\/set-goblen.ro\/blog\/wp-content\/uploads\/2015\/06\/82-212x300.jpg 212w, http:\/\/set-goblen.ro\/blog\/wp-content\/uploads\/2015\/06\/82-724x1024.jpg 724w, http:\/\/set-goblen.ro\/blog\/wp-content\/uploads\/2015\/06\/82.jpg 1405w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<div class=\"addtoany_share_save_container addtoany_content_top\"><div class=\"a2a_kit a2a_kit_size_32 addtoany_list a2a_target\" id=\"wpa2a_2\"><a class=\"a2a_button_facebook\" href=\"http:\/\/www.addtoany.com\/add_to\/facebook?linkurl=http%3A%2F%2Fset-goblen.ro%2Fblog%2Ffloare-nemuritoare-diagrame-goblen-gratis%2F8-3%2F&amp;linkname=8\" title=\"Facebook\" rel=\"nofollow\" target=\"_blank\"><\/a><a class=\"a2a_button_twitter\" href=\"http:\/\/www.addtoany.com\/add_to\/twitter?linkurl=http%3A%2F%2Fset-goblen.ro%2Fblog%2Ffloare-nemuritoare-diagrame-goblen-gratis%2F8-3%2F&amp;linkname=8\" title=\"Twitter\" rel=\"nofollow\" target=\"_blank\"><\/a><a class=\"a2a_button_google_plus\" href=\"http:\/\/www.addtoany.com\/add_to\/google_plus?linkurl=http%3A%2F%2Fset-goblen.ro%2Fblog%2Ffloare-nemuritoare-diagrame-goblen-gratis%2F8-3%2F&amp;linkname=8\" title=\"Google+\" rel=\"nofollow\" target=\"_blank\"><\/a><a class=\"a2a_dd addtoany_share_save\" href=\"https:\/\/www.addtoany.com\/share_save\"><\/a><\/div><\/div>"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1405,"height":1988,"file":"2015\/06\/82.jpg","sizes":{"thumbnail":{"file":"82-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/set-goblen.ro\/blog\/wp-content\/uploads\/2015\/06\/82-150x150.jpg"},"medium":{"file":"82-212x300.jpg","width":212,"height":300,"mime_type":"image\/jpeg","source_url":"http:\/\/set-goblen.ro\/blog\/wp-content\/uploads\/2015\/06\/82-212x300.jpg"},"large":{"file":"82-724x1024.jpg","width":724,"height":1024,"mime_type":"image\/jpeg","source_url":"http:\/\/set-goblen.ro\/blog\/wp-content\/uploads\/2015\/06\/82-724x1024.jpg"},"asteriathumb":{"file":"82-387x260.jpg","width":387,"height":260,"mime_type":"image\/jpeg","source_url":"http:\/\/set-goblen.ro\/blog\/wp-content\/uploads\/2015\/06\/82-387x260.jpg"},"full":{"file":"82.jpg","width":1405,"height":1988,"mime_type":"image\/jpeg","source_url":"http:\/\/set-goblen.ro\/blog\/wp-content\/uploads\/2015\/06\/82.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":392,"source_url":"http:\/\/set-goblen.ro\/blog\/wp-content\/uploads\/2015\/06\/82.jpg","_links":{"self":[{"href":"http:\/\/set-goblen.ro\/blog\/wp-json\/wp\/v2\/media\/401"}],"collection":[{"href":"http:\/\/set-goblen.ro\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/set-goblen.ro\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/set-goblen.ro\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/set-goblen.ro\/blog\/wp-json\/wp\/v2\/comments?post=401"}]}}